{"id":747,"date":"2021-09-10T08:50:30","date_gmt":"2021-09-10T06:50:30","guid":{"rendered":"https:\/\/www.cooksongold.es\/blog\/?p=747"},"modified":"2023-06-08T08:54:08","modified_gmt":"2023-06-08T06:54:08","slug":"como-fundir-plata-para-hacer-joyas","status":"publish","type":"post","link":"https:\/\/www.cookson-clal.es\/blog\/como-fundir-plata-para-hacer-joyas\/","title":{"rendered":"C\u00f3mo fundir plata para hacer joyas"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.cooksongold.es\/blog\/wp-content\/uploads\/2021\/09\/iStock-1202349865-1.jpg\" alt=\"Soldar plata\" class=\"wp-image-746\" width=\"493\" height=\"329\" srcset=\"https:\/\/www.cookson-clal.es\/blog\/wp-content\/uploads\/2021\/09\/iStock-1202349865-1.jpg 450w, https:\/\/www.cookson-clal.es\/blog\/wp-content\/uploads\/2021\/09\/iStock-1202349865-1-300x200.jpg 300w\" sizes=\"(max-width: 493px) 100vw, 493px\" \/><\/figure><\/div>\n\n\n<p>El proceso de <strong>fundir plata <\/strong>es relativamente sencillo, pero siempre y cuando se conozcan los principios fundamentales de los puntos de fusi\u00f3n del metal. La plata es un metal muy utilizado por los joyeros debido, precisamente, a su punto de fusi\u00f3n bajo. Por tanto, se trata de un metal ideal para aprender a fundir metales con el objetivo de realizar dise\u00f1os de joyer\u00eda m\u00e1s complejos y soldaduras m\u00e1s dif\u00edciles.<\/p>\n\n\n\n<p>Utilice nuestra gu\u00eda para principiantes para conocer <strong>c\u00f3mo se funde la plata<\/strong> que aparece a continuaci\u00f3n.<\/p><\/p><p><p><!--more Seguir leyendo... --><\/p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">El arte de fundir plata<\/h2>\n\n\n\n<p>Antes de empezar a trabajar y saber <strong>c\u00f3mo fundir plata artesanalmente<\/strong>, es muy importante que conozca el punto de fusi\u00f3n de la plata. De esta manera, sabr\u00e1 cu\u00e1l es el equipo de soldadura m\u00e1s adecuado que deber\u00e1 emplear y c\u00f3mo se funde la plata.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.cooksongold.es\/blog\/wp-content\/uploads\/2021\/09\/AdobeStock_102879768-1024x684-1-768x513-1.jpeg\" alt=\"Arte de fundir\" class=\"wp-image-745\" width=\"497\" height=\"332\" srcset=\"https:\/\/www.cookson-clal.es\/blog\/wp-content\/uploads\/2021\/09\/AdobeStock_102879768-1024x684-1-768x513-1.jpeg 768w, https:\/\/www.cookson-clal.es\/blog\/wp-content\/uploads\/2021\/09\/AdobeStock_102879768-1024x684-1-768x513-1-300x200.jpeg 300w\" sizes=\"(max-width: 497px) 100vw, 497px\" \/><\/figure><\/div>\n\n\n<h2 class=\"wp-block-heading\">\u00bfCu\u00e1l es el punto de fusi\u00f3n de la plata?<\/h2>\n\n\n\n<p>El <strong>punto de fusi\u00f3n de la plata<\/strong> depender\u00e1 del tipo de plata con el que est\u00e9 trabajando. Recuerde, por ejemplo, que si est\u00e1 usando plata de ley 925, esta por su composici\u00f3n tendr\u00e1 un punto de fusi\u00f3n m\u00e1s bajo que la plata pura o plata 999.<\/p>\n\n\n\n<p>Utilice la siguiente tabla para conocer los diferentes puntos de fusi\u00f3n de los tipos de plata m\u00e1s habituales:<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Tipos de plata<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>Punto de fusi\u00f3n<\/strong><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Plata de ley 925<\/td><td class=\"has-text-align-center\" data-align=\"center\">890\u00baC<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Plata Britannia<\/td><td class=\"has-text-align-center\" data-align=\"center\">940\u00baC<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Plata fina 999<\/td><td class=\"has-text-align-center\" data-align=\"center\">961\u00baC<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Diferentes formas de trabajar la plata<\/h2>\n\n\n\n<p>Hay que tener en cuenta que, en la mayor\u00eda de las ocasiones, las l\u00e1minas de plata no se funden completamente para crear nuevas piezas de joyer\u00eda. En su lugar, se sueldan peque\u00f1as piezas de plata entre s\u00ed o se sueldan fornituras al metal. Es por esto por lo que resulta recomendable conocer algunos de los conceptos t\u00e9cnicos asociados al calentamiento del metal a la hora de soldar. As\u00ed podr\u00e1 entender cu\u00e1les son los detalles a los que debe prestar m\u00e1s atenci\u00f3n cuando caliente la plata con un soplete de mano y c\u00f3mo fundir plata artesanalmente.<\/p>\n\n\n\n<p><strong>Recalentamiento:<\/strong><\/p>\n\n\n\n<p>El recalentamiento se produce cuando el metal se calienta para ablandar su estructura. Al trabajar con la plata, las part\u00edculas del metal se compactan, haciendo que el metal se vuelva menos maleable y m\u00e1s dif\u00edcil de trabajar. Recalentando la plata, o lo que es lo mismo, calent\u00e1ndola hasta que adquiera un color rojo cereza apagado, se consigue <strong>ablandar la estructura del metal <\/strong>para facilitar el trabajo. Una f\u00f3rmula para saber c\u00f3mo se trabaja la plata.<\/p>\n\n\n\n<p><strong>La mancha de fuego:<\/strong><\/p>\n\n\n\n<p>La mancha de fuego se produce cuando el contenido de cobre de la plata de ley se oxida. Algo que tiene lugar especialmente cuando el metal se calienta. La mancha de fuego se presenta como una tenue sombra de color oscuro en la superficie de la plata. Esta mancha se puede eliminar si se pule el metal repetidas veces. Si la mancha de fuego no se elimina, volver\u00e1 a aparecer en el momento que haya que pulir la pieza.<\/p>\n\n\n\n<p><strong>Enfriamiento:<\/strong><\/p>\n\n\n\n<p>El enfriamiento alude al proceso de <strong>enfriar la plata una vez que se haya calentado<\/strong>. Una vez que se retire la pieza de metal de la fuente de calor, se puede enfriar sumergi\u00e9ndola en un recipiente con agua. El enfriamiento es un proceso que se lleva a cabo despu\u00e9s de la soldadura o el recocido del metal. Un proceso imprescindible si desea saber c\u00f3mo se funde la plata.<\/p>\n\n\n\n<p><strong>Soldadura:<\/strong><\/p>\n\n\n\n<p>La soldadura consiste en unir dos piezas de metal utilizando el calor de un soplete y un fundente. Este proceso es fundamental cuando se desea fundir plata, ya que posee una temperatura de fusi\u00f3n inferior a la de este metal. As\u00ed la soldadura se fundir\u00e1 mucho antes que la plata, lo que reduce los riesgos de que se pueda da\u00f1ar.<\/p>\n\n\n\n<p><strong>Soldadura de plata:<\/strong><\/p>\n\n\n\n<p>La soldadura de plata se emplea para <strong>crear una uni\u00f3n entre dos piezas de plata de ley<\/strong>. Hay hasta cuatro tipos diferentes de soldadura de plata: dura, media, f\u00e1cil y extra f\u00e1cil. Cada uno de estos tipos posee una temperatura de fusi\u00f3n diferente. De esta forma, podr\u00e1 elegir la soldadura m\u00e1s adecuada y sabr\u00e1 c\u00f3mo trabajar la plata. La idea es que cada tipo de soldadura se utilice de manera progresiva, empleando en primer lugar la soldadura dura, ya que es aquella que tiene la temperatura de fusi\u00f3n m\u00e1s alta.<\/p>\n\n\n\n<p>Ahora que ya conoce cu\u00e1les son algunos de los conceptos y tecnicismos que se emplean para fundir la plata, est\u00e1 casi preparado para <strong>aprender a soldar metal y crear piezas de plata de ley m\u00e1s complejas<\/strong>. Para obtener m\u00e1s informaci\u00f3n sobre el proceso de soldadura, lea los art\u00edculos de nuestro blog: <a href=\"https:\/\/www.cooksongold.es\/blog\/como-soldar-plata\/\">C\u00f3mo soldar plata<\/a> o <a href=\"https:\/\/www.cooksongold.es\/blog\/10-herramientas-de-soldadura-imprescindibles-para-joyeria\/\">10 Herramientas de soldadura<\/a>.<\/p>\n\n\n\n<p>Aqu\u00ed puede ver la <a href=\"https:\/\/www.cookson-clal.es\/Metal-plata\/-Gama=Soldadura\/-Aleaci%C3%B3n=0\/-Forma=0\/-Dimensiones=0\/-Intervalo_de_fusi%C3%B3n=0\/-Temperatura_de_trabajo=0\/-Estado=0\/&amp;prdsearch=y\" target=\"_blank\" rel=\"noreferrer noopener\">soldadura de plata<\/a> que tenemos disponible.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El proceso de fundir plata es relativamente sencillo, pero siempre y cuando se conozcan los principios fundamentales de los puntos de fusi\u00f3n del metal. La plata es un metal muy utilizado por los joyeros debido, precisamente, a su punto de fusi\u00f3n bajo. Por tanto, se trata de un metal ideal para aprender a fundir metales [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[7,13],"tags":[160,76,31,28],"_links":{"self":[{"href":"https:\/\/www.cookson-clal.es\/blog\/wp-json\/wp\/v2\/posts\/747"}],"collection":[{"href":"https:\/\/www.cookson-clal.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cookson-clal.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cookson-clal.es\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cookson-clal.es\/blog\/wp-json\/wp\/v2\/comments?post=747"}],"version-history":[{"count":6,"href":"https:\/\/www.cookson-clal.es\/blog\/wp-json\/wp\/v2\/posts\/747\/revisions"}],"predecessor-version":[{"id":852,"href":"https:\/\/www.cookson-clal.es\/blog\/wp-json\/wp\/v2\/posts\/747\/revisions\/852"}],"wp:attachment":[{"href":"https:\/\/www.cookson-clal.es\/blog\/wp-json\/wp\/v2\/media?parent=747"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cookson-clal.es\/blog\/wp-json\/wp\/v2\/categories?post=747"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cookson-clal.es\/blog\/wp-json\/wp\/v2\/tags?post=747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}